{"id":28974,"date":"2023-08-30T16:37:52","date_gmt":"2023-08-30T14:37:52","guid":{"rendered":"https:\/\/hebergement2.ch\/?p=28974"},"modified":"2025-09-25T12:21:49","modified_gmt":"2025-09-25T10:21:49","slug":"less-et-le-ski-club-villars","status":"publish","type":"post","link":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars","title":{"rendered":"Episode 24: L&rsquo;ess et le ski club villars"},"content":{"rendered":"<h2>L&rsquo;ESS et le Ski Club Villars<\/h2>\n<p>Depuis sa fondation en 1932, l\u2019Ecole Suisse de Ski a de tous temps collabor\u00e9 avec le Ski-club de Villars en mettant \u00e0 sa disposition le savoir-faire de ses membres. De nombreux professeurs de l\u2019ESS, anciens champions ou entra\u00eeneurs dipl\u00f4m\u00e9s ont activement collabor\u00e9 pour la mise sur pied des principales courses de ski dans la station. De nos jours, la contribution respective des deux entit\u00e9s est souvent difficile \u00e0 dissocier.<\/p>\n<p>Dans les ann\u00e9es 70, Michel Daetwyler a \u0153uvr\u00e9 pour un rapprochement encore marqu\u00e9 entre les deux institutions. Depuis lors, les professeurs de l\u2019Ecole de Ski sont en charge de l\u2019entrainement des membres du Ski-club. Ces derniers participent \u00e9galement en nombres aux \u00ab Ski-Open \u00bb de l\u2019ESS, qui repr\u00e9sentent pour eux de bonnes courses d\u2019entra\u00eenement. D\u00e8s 1991, la collaboration s\u2019\u00e9tend aux plus jeunes puisque l\u2019ESS met sur pied les \u00ab pr\u00e9-OJ \u00bb, a\ufb01n d\u2019encadrer les enfants encore trop jeunes pour int\u00e9grer le Ski Club.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-large wp-image-28975\" src=\"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG-5-1024x731.jpg\" alt=\"\" width=\"800\" height=\"571\" srcset=\"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG-5-1024x731.jpg 1024w, https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG-5-300x214.jpg 300w, https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG-5-768x548.jpg 768w, https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG-5-1536x1096.jpg 1536w, https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG-5-2048x1461.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-large wp-image-28976\" src=\"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG_0048-1-1024x726.jpg\" alt=\"\" width=\"800\" height=\"567\" srcset=\"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG_0048-1-1024x726.jpg 1024w, https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG_0048-1-300x213.jpg 300w, https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG_0048-1-768x545.jpg 768w, https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG_0048-1-1536x1089.jpg 1536w, https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG_0048-1-2048x1452.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Cette collaboration a d\u00e9bouch\u00e9 sur un cercle vertueux : L\u2019ESS forme les jeunes du Ski-club, qui composent \u00e0 leur tour l\u2019essentiel de la rel\u00e8ve pour l\u2019ESS. Cette imbrication se retrouve de nos jours \u00e0 la direction du Ski-club. En effet, du pr\u00e9sident au chef alpin, six membres de l\u2019Ecole Suisse de Ski si\u00e8gent actuellement au comit\u00e9 du Ski-club.<\/p>\n<p>L\u2019ESS Villars a directement pro\ufb01t\u00e9 des nombreux champions form\u00e9s par le Ski-Club qui sont ensuite devenus professeurs de ski ; la plupart des dirigeants actuels de l\u2019ESS ont d\u2019ailleurs fait leurs gammes au Ski-club de Villars.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-large wp-image-28977\" src=\"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/Groupe-competition-2017-2018-1024x423.jpg\" alt=\"\" width=\"800\" height=\"330\" srcset=\"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/Groupe-competition-2017-2018-1024x423.jpg 1024w, https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/Groupe-competition-2017-2018-300x124.jpg 300w, https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/Groupe-competition-2017-2018-768x317.jpg 768w, https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/Groupe-competition-2017-2018-1536x634.jpg 1536w, https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/Groupe-competition-2017-2018-2048x845.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;ESS et le Ski Club Villars Depuis sa fondation en 1932, l\u2019Ecole Suisse de Ski a de tous temps collabor\u00e9 avec le Ski-club de Villars en mettant \u00e0 sa disposition le savoir-faire de ses membres. De nombreux professeurs de l\u2019ESS, anciens champions ou entra\u00eeneurs dipl\u00f4m\u00e9s ont activement collabor\u00e9 pour la mise sur pied des principales [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28975,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-28974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Episode 24: L&#039;ess et le ski club villars - ESS Villars<\/title>\n<meta name=\"description\" content=\"L&#039;ESS et le Ski Club Villars Depuis sa fondation en 1932, l\u2019Ecole Suisse de Ski a de tous temps collabor\u00e9 avec le Ski-club de Vill...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Episode 24: L&#039;ess et le ski club villars - ESS Villars\" \/>\n<meta property=\"og:description\" content=\"L&#039;ESS et le Ski Club Villars Depuis sa fondation en 1932, l\u2019Ecole Suisse de Ski a de tous temps collabor\u00e9 avec le Ski-club de Vill...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars\" \/>\n<meta property=\"og:site_name\" content=\"ESS Villars\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-30T14:37:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-25T10:21:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2471\" \/>\n\t<meta property=\"og:image:height\" content=\"1763\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin_ess_1234\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin_ess_1234\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/blogs\\\/item\\\/2563-episode-24-l-ess-et-le-ski-club-villars#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/blogs\\\/item\\\/2563-episode-24-l-ess-et-le-ski-club-villars\"},\"author\":{\"name\":\"Admin_ess_1234\",\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/#\\\/schema\\\/person\\\/0f30ecd734c125feb7718cb834b17b33\"},\"headline\":\"Episode 24: L&rsquo;ess et le ski club villars\",\"datePublished\":\"2023-08-30T14:37:52+00:00\",\"dateModified\":\"2025-09-25T10:21:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/blogs\\\/item\\\/2563-episode-24-l-ess-et-le-ski-club-villars\"},\"wordCount\":281,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/blogs\\\/item\\\/2563-episode-24-l-ess-et-le-ski-club-villars#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ess-villars.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/IMG-5.jpg\",\"articleSection\":[\"Histoire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/blogs\\\/item\\\/2563-episode-24-l-ess-et-le-ski-club-villars#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/blogs\\\/item\\\/2563-episode-24-l-ess-et-le-ski-club-villars\",\"url\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/blogs\\\/item\\\/2563-episode-24-l-ess-et-le-ski-club-villars\",\"name\":\"Episode 24: L'ess et le ski club villars - ESS Villars\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/blogs\\\/item\\\/2563-episode-24-l-ess-et-le-ski-club-villars#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/blogs\\\/item\\\/2563-episode-24-l-ess-et-le-ski-club-villars#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ess-villars.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/IMG-5.jpg\",\"datePublished\":\"2023-08-30T14:37:52+00:00\",\"dateModified\":\"2025-09-25T10:21:49+00:00\",\"description\":\"L'ESS et le Ski Club Villars Depuis sa fondation en 1932, l\u2019Ecole Suisse de Ski a de tous temps collabor\u00e9 avec le Ski-club de Vill...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/blogs\\\/item\\\/2563-episode-24-l-ess-et-le-ski-club-villars#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/blogs\\\/item\\\/2563-episode-24-l-ess-et-le-ski-club-villars\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/blogs\\\/item\\\/2563-episode-24-l-ess-et-le-ski-club-villars#primaryimage\",\"url\":\"https:\\\/\\\/ess-villars.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/IMG-5.jpg\",\"contentUrl\":\"https:\\\/\\\/ess-villars.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/IMG-5.jpg\",\"width\":2471,\"height\":1763},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/blogs\\\/item\\\/2563-episode-24-l-ess-et-le-ski-club-villars#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Episode 24: L&rsquo;ess et le ski club villars\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/\",\"name\":\"ESS Villars\",\"description\":\"Join the red legend !\",\"publisher\":{\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/#organization\",\"name\":\"ESS Villars\",\"url\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ess-villars.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/ESS_Villars_logo_png.png\",\"contentUrl\":\"https:\\\/\\\/ess-villars.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/ESS_Villars_logo_png.png\",\"width\":1181,\"height\":1181,\"caption\":\"ESS Villars\"},\"image\":{\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ess-villars.ch\\\/fr\\\/#\\\/schema\\\/person\\\/0f30ecd734c125feb7718cb834b17b33\",\"name\":\"Admin_ess_1234\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fa0ab8129cd20f0a7834bfabb7e7a1558862e46633c891c431236a50cc39ab9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fa0ab8129cd20f0a7834bfabb7e7a1558862e46633c891c431236a50cc39ab9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fa0ab8129cd20f0a7834bfabb7e7a1558862e46633c891c431236a50cc39ab9?s=96&d=mm&r=g\",\"caption\":\"Admin_ess_1234\"},\"sameAs\":[\"https:\\\/\\\/ess-villars.ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Episode 24: L'ess et le ski club villars - ESS Villars","description":"L'ESS et le Ski Club Villars Depuis sa fondation en 1932, l\u2019Ecole Suisse de Ski a de tous temps collabor\u00e9 avec le Ski-club de Vill...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars\/","og_locale":"fr_FR","og_type":"article","og_title":"Episode 24: L'ess et le ski club villars - ESS Villars","og_description":"L'ESS et le Ski Club Villars Depuis sa fondation en 1932, l\u2019Ecole Suisse de Ski a de tous temps collabor\u00e9 avec le Ski-club de Vill...","og_url":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars","og_site_name":"ESS Villars","article_published_time":"2023-08-30T14:37:52+00:00","article_modified_time":"2025-09-25T10:21:49+00:00","og_image":[{"width":2471,"height":1763,"url":"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG-5.jpg","type":"image\/jpeg"}],"author":"Admin_ess_1234","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Admin_ess_1234","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars#article","isPartOf":{"@id":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars"},"author":{"name":"Admin_ess_1234","@id":"https:\/\/ess-villars.ch\/fr\/#\/schema\/person\/0f30ecd734c125feb7718cb834b17b33"},"headline":"Episode 24: L&rsquo;ess et le ski club villars","datePublished":"2023-08-30T14:37:52+00:00","dateModified":"2025-09-25T10:21:49+00:00","mainEntityOfPage":{"@id":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars"},"wordCount":281,"commentCount":0,"publisher":{"@id":"https:\/\/ess-villars.ch\/fr\/#organization"},"image":{"@id":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars#primaryimage"},"thumbnailUrl":"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG-5.jpg","articleSection":["Histoire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars","url":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars","name":"Episode 24: L'ess et le ski club villars - ESS Villars","isPartOf":{"@id":"https:\/\/ess-villars.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars#primaryimage"},"image":{"@id":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars#primaryimage"},"thumbnailUrl":"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG-5.jpg","datePublished":"2023-08-30T14:37:52+00:00","dateModified":"2025-09-25T10:21:49+00:00","description":"L'ESS et le Ski Club Villars Depuis sa fondation en 1932, l\u2019Ecole Suisse de Ski a de tous temps collabor\u00e9 avec le Ski-club de Vill...","breadcrumb":{"@id":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars#primaryimage","url":"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG-5.jpg","contentUrl":"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/IMG-5.jpg","width":2471,"height":1763},{"@type":"BreadcrumbList","@id":"https:\/\/ess-villars.ch\/fr\/blogs\/item\/2563-episode-24-l-ess-et-le-ski-club-villars#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ess-villars.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Episode 24: L&rsquo;ess et le ski club villars"}]},{"@type":"WebSite","@id":"https:\/\/ess-villars.ch\/fr\/#website","url":"https:\/\/ess-villars.ch\/fr\/","name":"ESS Villars","description":"Join the red legend !","publisher":{"@id":"https:\/\/ess-villars.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ess-villars.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ess-villars.ch\/fr\/#organization","name":"ESS Villars","url":"https:\/\/ess-villars.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ess-villars.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/ESS_Villars_logo_png.png","contentUrl":"https:\/\/ess-villars.ch\/wp-content\/uploads\/2023\/08\/ESS_Villars_logo_png.png","width":1181,"height":1181,"caption":"ESS Villars"},"image":{"@id":"https:\/\/ess-villars.ch\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ess-villars.ch\/fr\/#\/schema\/person\/0f30ecd734c125feb7718cb834b17b33","name":"Admin_ess_1234","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5fa0ab8129cd20f0a7834bfabb7e7a1558862e46633c891c431236a50cc39ab9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5fa0ab8129cd20f0a7834bfabb7e7a1558862e46633c891c431236a50cc39ab9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5fa0ab8129cd20f0a7834bfabb7e7a1558862e46633c891c431236a50cc39ab9?s=96&d=mm&r=g","caption":"Admin_ess_1234"},"sameAs":["https:\/\/ess-villars.ch"]}]}},"_links":{"self":[{"href":"https:\/\/ess-villars.ch\/fr\/wp-json\/wp\/v2\/posts\/28974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ess-villars.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ess-villars.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ess-villars.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ess-villars.ch\/fr\/wp-json\/wp\/v2\/comments?post=28974"}],"version-history":[{"count":1,"href":"https:\/\/ess-villars.ch\/fr\/wp-json\/wp\/v2\/posts\/28974\/revisions"}],"predecessor-version":[{"id":28978,"href":"https:\/\/ess-villars.ch\/fr\/wp-json\/wp\/v2\/posts\/28974\/revisions\/28978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ess-villars.ch\/fr\/wp-json\/wp\/v2\/media\/28975"}],"wp:attachment":[{"href":"https:\/\/ess-villars.ch\/fr\/wp-json\/wp\/v2\/media?parent=28974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ess-villars.ch\/fr\/wp-json\/wp\/v2\/categories?post=28974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ess-villars.ch\/fr\/wp-json\/wp\/v2\/tags?post=28974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}